{"id":2889,"date":"2025-08-27T15:49:45","date_gmt":"2025-08-27T13:49:45","guid":{"rendered":"https:\/\/frenehard-michaux.eu\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/"},"modified":"2025-11-19T11:46:26","modified_gmt":"2025-11-19T10:46:26","slug":"frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis","status":"publish","type":"post","link":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/","title":{"rendered":"Fr\u00e9n\u00e9hard &amp; Michaux Holding, toegewijde partner van de Prix des Apprentis"},"content":{"rendered":"\n<p>In het kader van haar betrokkenheid bij jongeren en beroepsopleidingen kondigt de Groep Fr\u00e9n\u00e9hard &amp; Michaux met trots haar partnerschap aan met de Prix des Apprentis, georganiseerd door de Soci\u00e9t\u00e9 des Membres de la L\u00e9gion d&#8217;Honneur.<\/p>\n\n<p>Deze onderscheiding beloont de uitmuntendheid, persoonlijke investering en verdienste van jonge leerlingen en erkent hun prestaties met de steun van hun leraren en leermeesters. Door deel te nemen aan dit initiatief bevestigt de Groep haar inzet voor het ontwikkelen van vaardigheden en het bevorderen van stages, een belangrijk thema voor de toekomst.<\/p>\n\n<p>Jacques Fr\u00e9n\u00e9hard, voorzitter van de Raad van Commissarissen van de Groep en voorzitter van de jury voor het departement Orne, was aanwezig bij de prijsuitreiking. Hij vergezelde de winnaars samen met de prefect van Orne en de voorzitter van de lokale afdeling van de Soci\u00e9t\u00e9 des Membres de la L\u00e9gion d&#8217;Honneur.<\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In het kader van haar betrokkenheid bij jongeren en beroepsopleidingen kondigt de Groep Fr\u00e9n\u00e9hard &amp; Michaux met trots haar partnerschap aan met de Prix des Apprentis, georganiseerd door de Soci\u00e9t\u00e9 des Membres de la L\u00e9gion d&#8217;Honneur. Deze onderscheiding beloont de uitmuntendheid, persoonlijke investering en verdienste van jonge leerlingen en erkent hun prestaties met de steun [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":2890,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fr\u00e9n\u00e9hard &amp; Michaux Holding, toegewijde partner van de Prix des Apprentis - Frenehard &amp; Michaux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fr\u00e9n\u00e9hard &amp; Michaux Holding, toegewijde partner van de Prix des Apprentis - Frenehard &amp; Michaux\" \/>\n<meta property=\"og:description\" content=\"In het kader van haar betrokkenheid bij jongeren en beroepsopleidingen kondigt de Groep Fr\u00e9n\u00e9hard &amp; Michaux met trots haar partnerschap aan met de Prix des Apprentis, georganiseerd door de Soci\u00e9t\u00e9 des Membres de la L\u00e9gion d&#8217;Honneur. Deze onderscheiding beloont de uitmuntendheid, persoonlijke investering en verdienste van jonge leerlingen en erkent hun prestaties met de steun [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/\" \/>\n<meta property=\"og:site_name\" content=\"Frenehard &amp; Michaux\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-27T13:49:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T10:46:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frenehard-michaux.eu\/wp-content\/uploads\/sites\/8\/2025\/08\/1750162258723.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dvilla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"dvilla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\\\/\"},\"author\":{\"name\":\"dvilla\",\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/#\\\/schema\\\/person\\\/bac7436d73d96053fa218d6fb220083d\"},\"headline\":\"Fr\u00e9n\u00e9hard &amp; Michaux Holding, toegewijde partner van de Prix des Apprentis\",\"datePublished\":\"2025-08-27T13:49:45+00:00\",\"dateModified\":\"2025-11-19T10:46:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\\\/\"},\"wordCount\":162,\"publisher\":{\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenehard-michaux.eu\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/08\\\/1750162258723.jpeg\",\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\\\/\",\"url\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\\\/\",\"name\":\"Fr\u00e9n\u00e9hard &amp; Michaux Holding, toegewijde partner van de Prix des Apprentis - Frenehard &amp; Michaux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenehard-michaux.eu\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/08\\\/1750162258723.jpeg\",\"datePublished\":\"2025-08-27T13:49:45+00:00\",\"dateModified\":\"2025-11-19T10:46:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frenehard-michaux.eu\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/08\\\/1750162258723.jpeg\",\"contentUrl\":\"https:\\\/\\\/frenehard-michaux.eu\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/08\\\/1750162258723.jpeg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fr\u00e9n\u00e9hard &amp; Michaux Holding, toegewijde partner van de Prix des Apprentis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/\",\"name\":\"Frenehard &amp; Michaux\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/#organization\",\"name\":\"Frenehard &amp; Michaux\",\"url\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/frenehard-michaux.eu\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/09\\\/Frenehard-Michaux_RVB.svg\",\"contentUrl\":\"https:\\\/\\\/frenehard-michaux.eu\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/09\\\/Frenehard-Michaux_RVB.svg\",\"caption\":\"Frenehard &amp; Michaux\"},\"image\":{\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frenehard-michaux.eu\\\/nl\\\/#\\\/schema\\\/person\\\/bac7436d73d96053fa218d6fb220083d\",\"name\":\"dvilla\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fr\u00e9n\u00e9hard &amp; Michaux Holding, toegewijde partner van de Prix des Apprentis - Frenehard &amp; Michaux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/","og_locale":"nl_NL","og_type":"article","og_title":"Fr\u00e9n\u00e9hard &amp; Michaux Holding, toegewijde partner van de Prix des Apprentis - Frenehard &amp; Michaux","og_description":"In het kader van haar betrokkenheid bij jongeren en beroepsopleidingen kondigt de Groep Fr\u00e9n\u00e9hard &amp; Michaux met trots haar partnerschap aan met de Prix des Apprentis, georganiseerd door de Soci\u00e9t\u00e9 des Membres de la L\u00e9gion d&#8217;Honneur. Deze onderscheiding beloont de uitmuntendheid, persoonlijke investering en verdienste van jonge leerlingen en erkent hun prestaties met de steun [&hellip;]","og_url":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/","og_site_name":"Frenehard &amp; Michaux","article_published_time":"2025-08-27T13:49:45+00:00","article_modified_time":"2025-11-19T10:46:26+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/frenehard-michaux.eu\/wp-content\/uploads\/sites\/8\/2025\/08\/1750162258723.jpeg","type":"image\/jpeg"}],"author":"dvilla","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"dvilla","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/#article","isPartOf":{"@id":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/"},"author":{"name":"dvilla","@id":"https:\/\/frenehard-michaux.eu\/nl\/#\/schema\/person\/bac7436d73d96053fa218d6fb220083d"},"headline":"Fr\u00e9n\u00e9hard &amp; Michaux Holding, toegewijde partner van de Prix des Apprentis","datePublished":"2025-08-27T13:49:45+00:00","dateModified":"2025-11-19T10:46:26+00:00","mainEntityOfPage":{"@id":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/"},"wordCount":162,"publisher":{"@id":"https:\/\/frenehard-michaux.eu\/nl\/#organization"},"image":{"@id":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/#primaryimage"},"thumbnailUrl":"https:\/\/frenehard-michaux.eu\/wp-content\/uploads\/sites\/8\/2025\/08\/1750162258723.jpeg","inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/","url":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/","name":"Fr\u00e9n\u00e9hard &amp; Michaux Holding, toegewijde partner van de Prix des Apprentis - Frenehard &amp; Michaux","isPartOf":{"@id":"https:\/\/frenehard-michaux.eu\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/#primaryimage"},"image":{"@id":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/#primaryimage"},"thumbnailUrl":"https:\/\/frenehard-michaux.eu\/wp-content\/uploads\/sites\/8\/2025\/08\/1750162258723.jpeg","datePublished":"2025-08-27T13:49:45+00:00","dateModified":"2025-11-19T10:46:26+00:00","breadcrumb":{"@id":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/#primaryimage","url":"https:\/\/frenehard-michaux.eu\/wp-content\/uploads\/sites\/8\/2025\/08\/1750162258723.jpeg","contentUrl":"https:\/\/frenehard-michaux.eu\/wp-content\/uploads\/sites\/8\/2025\/08\/1750162258723.jpeg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/frenehard-michaux.eu\/nl\/frenehard-michaux-holding-toegewijde-partner-van-de-prix-des-apprentis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/frenehard-michaux.eu\/nl\/accueil\/"},{"@type":"ListItem","position":2,"name":"Fr\u00e9n\u00e9hard &amp; Michaux Holding, toegewijde partner van de Prix des Apprentis"}]},{"@type":"WebSite","@id":"https:\/\/frenehard-michaux.eu\/nl\/#website","url":"https:\/\/frenehard-michaux.eu\/nl\/","name":"Frenehard &amp; Michaux","description":"","publisher":{"@id":"https:\/\/frenehard-michaux.eu\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frenehard-michaux.eu\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/frenehard-michaux.eu\/nl\/#organization","name":"Frenehard &amp; Michaux","url":"https:\/\/frenehard-michaux.eu\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/frenehard-michaux.eu\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/frenehard-michaux.eu\/wp-content\/uploads\/sites\/8\/2025\/09\/Frenehard-Michaux_RVB.svg","contentUrl":"https:\/\/frenehard-michaux.eu\/wp-content\/uploads\/sites\/8\/2025\/09\/Frenehard-Michaux_RVB.svg","caption":"Frenehard &amp; Michaux"},"image":{"@id":"https:\/\/frenehard-michaux.eu\/nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/frenehard-michaux.eu\/nl\/#\/schema\/person\/bac7436d73d96053fa218d6fb220083d","name":"dvilla"}]}},"_links":{"self":[{"href":"https:\/\/frenehard-michaux.eu\/nl\/wp-json\/wp\/v2\/posts\/2889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenehard-michaux.eu\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frenehard-michaux.eu\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frenehard-michaux.eu\/nl\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/frenehard-michaux.eu\/nl\/wp-json\/wp\/v2\/comments?post=2889"}],"version-history":[{"count":1,"href":"https:\/\/frenehard-michaux.eu\/nl\/wp-json\/wp\/v2\/posts\/2889\/revisions"}],"predecessor-version":[{"id":2891,"href":"https:\/\/frenehard-michaux.eu\/nl\/wp-json\/wp\/v2\/posts\/2889\/revisions\/2891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenehard-michaux.eu\/nl\/wp-json\/wp\/v2\/media\/2890"}],"wp:attachment":[{"href":"https:\/\/frenehard-michaux.eu\/nl\/wp-json\/wp\/v2\/media?parent=2889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}